{"id":14031,"date":"2024-10-22T16:57:07","date_gmt":"2024-10-22T14:57:07","guid":{"rendered":"https:\/\/integrasostenibilidad.online\/aviso-legal\/"},"modified":"2024-11-18T12:51:54","modified_gmt":"2024-11-18T11:51:54","slug":"aviso-legal","status":"publish","type":"page","link":"https:\/\/integrasostenibilidad.online\/pt-pt\/aviso-legal\/","title":{"rendered":"Aviso legal"},"content":{"rendered":"<h3>I. INFORMACI\u00d3N GENERAL<\/h3>\n<p>En cumplimiento con el deber de informaci\u00f3n dispuesto en la Ley 34\/2002 de Servicios de la Sociedad de la Informaci\u00f3n y el Comercio Electr\u00f3nico (LSSI-CE) de 11 de julio, se facilitan a continuaci\u00f3n los siguientes datos de informaci\u00f3n general de este sitio web:<\/p>\n<p>La titularidad de este sitio web, https:\/\/integraserviciosgenerales.es\/, (en adelante, Sitio Web) la ostenta: INTEGRA FACILITY SERVICES, S.L., provista de NIF: B91787424 , y cuyos datos de contacto son:<\/p>\n<p>Direcci\u00f3n: C\/ IMPRENTA, 29 \u2013 M\u00f3d. 1 41016 SEVILLA<\/p>\n<p>Email de contacto: mtorres@integrafacility.es<\/p>\n<h3>II. T\u00c9RMINOS Y CONDICIONES GENERALES DE USO<\/h3>\n<h4>El objeto de las condiciones: El Sitio Web<\/h4>\n<p>El objeto de las presentes Condiciones Generales de Uso (en adelante, Condiciones) es regular el acceso y la utilizaci\u00f3n del Sitio Web. A los efectos de las presentes Condiciones se entender\u00e1 como Sitio Web: la apariencia externa de los interfaces de pantalla, tanto de forma est\u00e1tica como de forma din\u00e1mica, es decir, el \u00e1rbol de navegaci\u00f3n; y todos los elementos integrados tanto en los interfaces de pantalla como en el \u00e1rbol de navegaci\u00f3n (en adelante, Contenidos) y todos aquellos servicios o recursos en l\u00ednea que en su caso ofrezca a los Usuarios (en adelante, Servicios).<\/p>\n<p>se reserva la facultad de modificar, en cualquier momento, y sin aviso previo, la presentaci\u00f3n y configuraci\u00f3n del Sitio Web y de los Contenidos y Servicios que en \u00e9l pudieran estar incorporados. El Usuario reconoce y acepta que en cualquier momento pueda interrumpir, desactivar y\/o cancelar cualquiera de estos elementos que se integran en el Sitio Web o el acceso a los mismos.<\/p>\n<p>El acceso al Sitio Web por el Usuario tiene car\u00e1cter libre y, por regla general, es gratuito sin que el Usuario tenga que proporcionar una contraprestaci\u00f3n para poder disfrutar de ello, salvo en lo relativo al coste de conexi\u00f3n a trav\u00e9s de la red de telecomunicaciones suministrada por el proveedor de acceso que hubiere contratado el Usuario.<\/p>\n<p>La utilizaci\u00f3n de los Contenidos no requiere previa suscripci\u00f3n o registro alguno.<\/p>\n<h4>El Usuario<\/h4>\n<p>El acceso, la navegaci\u00f3n y uso del Sitio Web, confiere la condici\u00f3n de Usuario, por lo que se aceptan, desde que se inicia la navegaci\u00f3n por el Sitio Web, todas las Condiciones aqu\u00ed establecidas, as\u00ed como sus ulteriores modificaciones, sin perjuicio de la aplicaci\u00f3n de la correspondiente normativa legal de obligado cumplimiento seg\u00fan el caso. Dada la relevancia de lo anterior, se recomienda al Usuario leerlas cada vez que visite el Sitio Web.<\/p>\n<p>El Sitio Web de proporciona gran diversidad de informaci\u00f3n, servicios y datos. El Usuario asume su responsabilidad para realizar un uso correcto del Sitio Web. Esta responsabilidad se extender\u00e1 a:<\/p>\n<ul>\n<li>Un uso de la informaci\u00f3n, Contenidos y\/o Servicios y datos ofrecidos por sin que sea contrario a lo dispuesto por las presentes Condiciones, la Ley, la moral o el orden p\u00fablico, o que de cualquier otro modo puedan suponer lesi\u00f3n de los derechos de terceros o del mismo funcionamiento del Sitio Web.<\/li>\n<li>La veracidad y licitud de las informaciones aportadas por el Usuario en los formularios extendidos por para el acceso a ciertos Contenidos o Servicios ofrecidos por el Sitio Web. En todo caso, el Usuario notificar\u00e1 de forma inmediata a acerca de cualquier hecho que permita el uso indebido de la informaci\u00f3n registrada en dichos formularios, tales como, pero no solo, el robo, extrav\u00edo, o el acceso no autorizado a identificadores y\/o contrase\u00f1as, con el fin de proceder a su inmediata cancelaci\u00f3n.<\/li>\n<\/ul>\n<p>El mero acceso a este Sitio Web no supone entablar ning\u00fan tipo de relaci\u00f3n de car\u00e1cter comercial entre y el Usuario.<\/p>\n<p>Siempre en el respeto de la legislaci\u00f3n vigente, este Sitio Web de se dirige a todas las personas, sin importar su edad, que puedan acceder y\/o navegar por las p\u00e1ginas del Sitio Web.<\/p>\n<h3>III. ACCESO Y NAVEGACI\u00d3N EN EL SITIO WEB: EXCLUSI\u00d3N DE GARANT\u00cdAS Y RESPONSABILIDAD<\/h3>\n<p>no garantiza la continuidad, disponibilidad y utilidad del Sitio Web, ni de los Contenidos o Servicios. har\u00e1 todo lo posible por el buen funcionamiento del Sitio Web, sin embargo, no se responsabiliza ni garantiza que el acceso a este Sitio Web no vaya a ser ininterrumpido o que est\u00e9 libre de error.<\/p>\n<p>Tampoco se responsabiliza o garantiza que el contenido o software al que pueda accederse a trav\u00e9s de este Sitio Web, est\u00e9 libre de error o cause un da\u00f1o al sistema inform\u00e1tico (software y hardware) del Usuario. En ning\u00fan caso ser\u00e1 responsable por las p\u00e9rdidas, da\u00f1os o perjuicios de cualquier tipo que surjan por el acceso, navegaci\u00f3n y el uso del Sitio Web, incluy\u00e9ndose, pero no limit\u00e1ndose, a los ocasionados a los sistemas inform\u00e1ticos o los provocados por la introducci\u00f3n de virus.<\/p>\n<p>tampoco se hace responsable de los da\u00f1os que pudiesen ocasionarse a los usuarios por un uso inadecuado de este Sitio Web. En particular, no se hace responsable en modo alguno de las ca\u00eddas, interrupciones, falta o defecto de las telecomunicaciones que pudieran ocurrir.<\/p>\n<h3>IV. POL\u00cdTICA DE ENLACES<\/h3>\n<p>Se informa que el Sitio Web de pone o puede poner a disposici\u00f3n de los Usuarios medios de enlace (como, entre otros, links, banners, botones), directorios y motores de b\u00fasqueda que permiten a los Usuarios acceder a sitios web pertenecientes y\/o gestionados por terceros.<\/p>\n<p>La instalaci\u00f3n de estos enlaces, directorios y motores de b\u00fasqueda en el Sitio Web tiene por objeto facilitar a los Usuarios la b\u00fasqueda de y acceso a la informaci\u00f3n disponible en Internet, sin que pueda considerarse una sugerencia, recomendaci\u00f3n o invitaci\u00f3n para la visita de los mismos.<\/p>\n<p>no ofrece ni comercializa por s\u00ed ni por medio de terceros los productos y\/o servicios disponibles en dichos sitios enlazados.<\/p>\n<p>Asimismo, tampoco garantizar\u00e1 la disponibilidad t\u00e9cnica, exactitud, veracidad, validez o legalidad de sitios ajenos a su propiedad a los que se pueda acceder por medio de los enlaces.<\/p>\n<p>en ning\u00fan caso revisar\u00e1 o controlar\u00e1 el contenido de otros sitios web, as\u00ed como tampoco aprueba, examina ni hace propios los productos y servicios, contenidos, archivos y cualquier otro material existente en los referidos sitios enlazados.<\/p>\n<p>no asume ninguna responsabilidad por los da\u00f1os y perjuicios que pudieran producirse por el acceso, uso, calidad o licitud de los contenidos, comunicaciones, opiniones, productos y servicios de los sitios web no gestionados por y que sean enlazados en este Sitio Web.<\/p>\n<p>El Usuario o tercero que realice un hiperv\u00ednculo desde una p\u00e1gina web de otro, distinto, sitio web al Sitio Web de deber\u00e1 saber que:<\/p>\n<p>No se permite la reproducci\u00f3n \u2014total o parcialmente\u2014 de ninguno de los Contenidos y\/o Servicios del Sitio Web sin autorizaci\u00f3n expresa de .<\/p>\n<p>No se permite tampoco ninguna manifestaci\u00f3n falsa, inexacta o incorrecta sobre el Sitio Web de , ni sobre los Contenidos y\/o Servicios del mismo.<\/p>\n<p>A excepci\u00f3n del hiperv\u00ednculo, el sitio web en el que se establezca dicho hiperenlace no contendr\u00e1 ning\u00fan elemento, de este Sitio Web, protegido como propiedad intelectual por el ordenamiento jur\u00eddico espa\u00f1ol, salvo autorizaci\u00f3n expresa de .<\/p>\n<p>El establecimiento del hiperv\u00ednculo no implicar\u00e1 la existencia de relaciones entre y el titular del sitio web desde el cual se realice, ni el conocimiento y aceptaci\u00f3n de de los contenidos, servicios y\/o actividades ofrecidas en dicho sitio web, y viceversa.<\/p>\n<h3>V. PROPIEDAD INTELECTUAL E INDUSTRIAL<\/h3>\n<p>por s\u00ed o como parte cesionaria, es titular de todos los derechos de propiedad intelectual e industrial del Sitio Web, as\u00ed como de los elementos contenidos en el mismo (a t\u00edtulo enunciativo y no exhaustivo, im\u00e1genes, sonido, audio, v\u00eddeo, software o textos, marcas o logotipos, combinaciones de colores, estructura y dise\u00f1o, selecci\u00f3n de materiales usados, programas de ordenador necesarios para su funcionamiento, acceso y uso, etc.). Ser\u00e1n, por consiguiente, obras protegidas como propiedad intelectual por el ordenamiento jur\u00eddico espa\u00f1ol, si\u00e9ndoles aplicables tanto la normativa espa\u00f1ola y comunitaria en este campo, como los tratados internacionales relativos a la materia y suscritos por Espa\u00f1a.<\/p>\n<p>Todos los derechos reservados. En virtud de lo dispuesto en la Ley de Propiedad Intelectual, quedan expresamente prohibidas la reproducci\u00f3n, la distribuci\u00f3n y la comunicaci\u00f3n p\u00fablica, incluida su modalidad de puesta a disposici\u00f3n, de la totalidad o parte de los contenidos de esta p\u00e1gina web, con fines comerciales, en cualquier soporte y por cualquier medio t\u00e9cnico, sin la autorizaci\u00f3n de .<\/p>\n<p>El Usuario se compromete a respetar los derechos de propiedad intelectual e industrial de . Podr\u00e1 visualizar los elementos del Sitio Web o incluso imprimirlos, copiarlos y almacenarlos en el disco duro de su ordenador o en cualquier otro soporte f\u00edsico siempre y cuando sea, exclusivamente, para su uso personal. El Usuario, sin embargo, no podr\u00e1 suprimir, alterar, o manipular cualquier dispositivo de protecci\u00f3n o sistema de seguridad que estuviera instalado en el Sitio Web.<\/p>\n<p>En caso de que el Usuario o tercero considere que cualquiera de los Contenidos del Sitio Web suponga una violaci\u00f3n de los derechos de protecci\u00f3n de la propiedad intelectual, deber\u00e1 comunicarlo inmediatamente a a trav\u00e9s de los datos de contacto del apartado de INFORMACI\u00d3N GENERAL de este Aviso Legal y Condiciones Generales de Uso.<\/p>\n<h3>VI. ACCIONES LEGALES, LEGISLACI\u00d3N APLICABLE Y JURISDICCI\u00d3N<\/h3>\n<p>se reserva la facultad de presentar las acciones civiles o penales que considere necesarias por la utilizaci\u00f3n indebida del Sitio Web y Contenidos, o por el incumplimiento de las presentes Condiciones.<\/p>\n<p>La relaci\u00f3n entre el Usuario y se regir\u00e1 por la normativa vigente y de aplicaci\u00f3n en el territorio espa\u00f1ol. De surgir cualquier controversia en relaci\u00f3n con la interpretaci\u00f3n y\/o a la aplicaci\u00f3n de estas Condiciones las partes someter\u00e1n sus conflictos a la jurisdicci\u00f3n ordinaria someti\u00e9ndose a los jueces y tribunales que correspondan conforme a derecho.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I. INFORMACI\u00d3N GENERAL En cumplimiento con el deber de informaci\u00f3n dispuesto en la Ley 34\/2002 de Servicios de la Sociedad [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":14003,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-14031","page","type-page","status-publish","has-post-thumbnail","hentry"],"uagb_featured_image_src":{"full":["https:\/\/integrasostenibilidad.online\/wp-content\/uploads\/2024\/10\/fondo-gris.jpg",1920,158,false],"thumbnail":["https:\/\/integrasostenibilidad.online\/wp-content\/uploads\/2024\/10\/fondo-gris-150x150.jpg",150,150,true],"medium":["https:\/\/integrasostenibilidad.online\/wp-content\/uploads\/2024\/10\/fondo-gris-300x25.jpg",300,25,true],"medium_large":["https:\/\/integrasostenibilidad.online\/wp-content\/uploads\/2024\/10\/fondo-gris-768x63.jpg",768,63,true],"large":["https:\/\/integrasostenibilidad.online\/wp-content\/uploads\/2024\/10\/fondo-gris-1024x84.jpg",1024,84,true],"1536x1536":["https:\/\/integrasostenibilidad.online\/wp-content\/uploads\/2024\/10\/fondo-gris-1536x126.jpg",1536,126,true],"2048x2048":["https:\/\/integrasostenibilidad.online\/wp-content\/uploads\/2024\/10\/fondo-gris.jpg",1920,158,false]},"uagb_author_info":{"display_name":"Integra","author_link":"https:\/\/integrasostenibilidad.online\/pt-pt\/author\/infointegraserviciosgenerales-es\/"},"uagb_comment_info":0,"uagb_excerpt":"I. INFORMACI\u00d3N GENERAL En cumplimiento con el deber de informaci\u00f3n dispuesto en la Ley 34\/2002 de Servicios de la Sociedad [&hellip;]","_links":{"self":[{"href":"https:\/\/integrasostenibilidad.online\/pt-pt\/wp-json\/wp\/v2\/pages\/14031","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/integrasostenibilidad.online\/pt-pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/integrasostenibilidad.online\/pt-pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/integrasostenibilidad.online\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/integrasostenibilidad.online\/pt-pt\/wp-json\/wp\/v2\/comments?post=14031"}],"version-history":[{"count":1,"href":"https:\/\/integrasostenibilidad.online\/pt-pt\/wp-json\/wp\/v2\/pages\/14031\/revisions"}],"predecessor-version":[{"id":14032,"href":"https:\/\/integrasostenibilidad.online\/pt-pt\/wp-json\/wp\/v2\/pages\/14031\/revisions\/14032"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/integrasostenibilidad.online\/pt-pt\/wp-json\/wp\/v2\/media\/14003"}],"wp:attachment":[{"href":"https:\/\/integrasostenibilidad.online\/pt-pt\/wp-json\/wp\/v2\/media?parent=14031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}